{"id":997,"date":"2025-03-25T08:50:49","date_gmt":"2025-03-25T08:50:49","guid":{"rendered":"https:\/\/new.al-rabiyah.com\/?page_id=997"},"modified":"2025-05-04T04:43:58","modified_gmt":"2025-05-04T04:43:58","slug":"%d8%a7%d9%84%d9%88%d8%b8%d8%a7%d8%a6%d9%81","status":"publish","type":"page","link":"https:\/\/al-rabiyah.com\/ar\/%d8%a7%d9%84%d9%88%d8%b8%d8%a7%d8%a6%d9%81\/","title":{"rendered":"\u0627\u0644\u0648\u0638\u0627\u0626\u0641"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"997\" class=\"elementor elementor-997 elementor-106\" data-elementor-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:&quot;yes&quot;,&quot;profecient_custom_cursor_inner_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_custom_cursor_outer_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_custom_cursor_outer_color&quot;:&quot;#3267FF&quot;,&quot;profecient_custom_cursor_outer_blend&quot;:&quot;normal&quot;,&quot;profecient_custom_cursor_outer_type&quot;:&quot;solid&quot;,&quot;profecient_custom_cursor_outer_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.5,&quot;sizes&quot;:&quot;&quot;},&quot;profecient_custom_cursor_inner_color&quot;:&quot;#FFFFFF&quot;,&quot;profecient_custom_cursor_inner_blend&quot;:&quot;difference&quot;,&quot;profecient_custom_cursor_inner_type&quot;:&quot;none&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f28fa60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f28fa60\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3034cf16\" data-id=\"3034cf16\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f311766 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"f311766\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u0627\u0644\u0648\u0638\u0627\u0626\u0641\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74abd989 elementor-widget elementor-widget-jkit_heading\" data-id=\"74abd989\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"jkit_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-heading  align-center align-tablet- align-mobile- jeg_module___6a580cac5b710\" ><div class=\"heading-section-title  display-inline\"><h2 class=\"heading-title\">\u0627\u0646\u0636\u0645<span class=\"style-gradient\"><span> \u0644\u0641\u0631\u064a\u0642\u0646\u0627!<\/span><\/span><\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63daed73 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"63daed73\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0646\u062d\u0646 \u0646\u0639\u0645\u0644 \u0639\u0644\u0649 \u0628\u0646\u0627\u0621 \u0645\u0633\u062a\u0642\u0628\u0644 \u0627\u0644\u0627\u0628\u062a\u0643\u0627\u0631 \u0627\u0644\u0637\u0628\u064a \u0648\u0627\u0644\u0645\u062e\u062a\u0628\u0631\u064a \u0641\u064a \u062c\u0645\u064a\u0639 \u0623\u0646\u062d\u0627\u0621 \u0627\u0644\u0645\u0646\u0637\u0642\u0629 &#8211; \u0648\u0646\u0628\u062d\u062b \u0639\u0646 \u0623\u0634\u062e\u0627\u0635 \u0645\u062a\u062d\u0645\u0633\u064a\u0646 \u0644\u0644\u0627\u0646\u0636\u0645\u0627\u0645 \u0625\u0644\u064a\u0646\u0627.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d3c7a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d3c7a2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-adfa779\" data-id=\"adfa779\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bb5d3d elementor-widget elementor-widget-metform\" data-id=\"9bb5d3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"metform.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"mf-response-props-id-1006\" data-previous-steps-style=\"\" data-editswitchopen=\"\" data-response_type=\"alert\" data-erroricon=\"fas fa-exclamation-triangle\" data-successicon=\"fas fa-check\" data-messageposition=\"top\" class=\"   mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"1006\" >\n\t\t\t\t\n\t\t\t<div class=\"mf-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-9bb5d3d-1006\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"1006\"\r\n\t\t\tdata-action=\"https:\/\/al-rabiyah.com\/ar\/wp-json\/metform\/v1\/entries\/insert\/1006\"\r\n\t\t\tdata-wp-nonce=\"ad23db1741\"\r\n\t\t\tdata-form-nonce=\"0c40517afe\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\tdata-payment-submit-before=\"0\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-1006\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"1006\" className=\"elementor elementor-1006\" data-elementor-post-type=\"metform-form\">\n\t\t\t\t\t\t<section className=\"elementor-section elementor-top-section elementor-element elementor-element-26ea9738 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"26ea9738\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c8f3e4b\" data-id=\"7c8f3e4b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-2a9965b8 elementor-widget elementor-widget-heading\" data-id=\"2a9965b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t<h3 className=\"elementor-heading-title elementor-size-default\">\u0646\u0645\u0648\u0630\u062c \u0637\u0644\u0628 \u0627\u0644\u0648\u0638\u0627\u0626\u0641 - \u0634\u0631\u0643\u0629 \u062c\u064a\u0646 \u0627\u0644\u062a\u0642\u0646\u064a\u0629 <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-a2880e5 elementor-widget elementor-widget-heading\" data-id=\"a2880e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t<h3 className=\"elementor-heading-title elementor-size-default\">\u064a\u0631\u062c\u0649 \u062a\u0639\u0628\u0626\u0629 \u0627\u0644\u0646\u0645\u0648\u0630\u062c \u0623\u062f\u0646\u0627\u0647 (\u062a\u0642\u062f\u0645 \u0644\u0644\u0648\u0638\u064a\u0641\u0629 \u0627\u0644\u062a\u064a \u062a\u062a\u0646\u0627\u0633\u0628 \u0645\u0639 \u0645\u0647\u0627\u0631\u0627\u062a\u0643 \u0641\u0642\u0637).<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-6a37e2f9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6a37e2f9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-24dd7809\" data-id=\"24dd7809\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-184663a1 elementor-widget elementor-widget-mf-text\" data-id=\"184663a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-first-name-ar&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-184663a1\">\r\n\t\t\t\t\t${ parent.decodeEntities(`\u0627\u0644\u0627\u0633\u0645 \u0627\u0644\u0623\u0648\u0644`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-184663a1\"\r\n\t\t\t\tname=\"mf-first-name-ar\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`\u0627\u0644\u0627\u0633\u0645 \u0627\u0644\u0623\u0648\u0644`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-first-name-ar'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-first-name-ar\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e243baf\" data-id=\"1e243baf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-763108f5 elementor-widget elementor-widget-mf-text\" data-id=\"763108f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-last-name-ar&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-763108f5\">\r\n\t\t\t\t\t${ parent.decodeEntities(`\u0627\u0644\u0627\u0633\u0645 \u0627\u0644\u0623\u062e\u064a\u0631`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-763108f5\"\r\n\t\t\t\tname=\"mf-last-name-ar\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`\u0627\u0644\u0627\u0633\u0645 \u0627\u0644\u0623\u062e\u064a\u0631`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-last-name-ar'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-last-name-ar\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-897112e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"897112e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1be78a4\" data-id=\"1be78a4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-252523e elementor-widget elementor-widget-mf-email\" data-id=\"252523e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-email-ar&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-email-252523e\">\r\n\t\t\t\t\t${ parent.decodeEntities(`\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input \" \r\n\t\t\t\tid=\"mf-input-email-252523e\" \r\n\t\t\t\tname=\"mf-email-ar\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a`) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['mf-email-ar'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"mf-email-ar\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-49e2c7f\" data-id=\"49e2c7f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-20deb7b9 elementor-widget elementor-widget-mf-text\" data-id=\"20deb7b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-Mobile-ar&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-20deb7b9\">\r\n\t\t\t\t\t${ parent.decodeEntities(`\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-20deb7b9\"\r\n\t\t\t\tname=\"mf-Mobile-ar\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641 \u0645\u0639 \u0645\u0641\u062a\u0627\u062d \u0627\u0644\u062f\u0648\u0644\u0629`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-Mobile-ar'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-Mobile-ar\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-b5dd6c0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b5dd6c0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5394375\" data-id=\"5394375\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-64b627a elementor-widget elementor-widget-mf-select\" data-id=\"64b627a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-Gender-ar&quot;,&quot;mf_input_list&quot;:[{&quot;mf_input_option_text&quot;:&quot;\\u0630\\u0643\\u0631&quot;,&quot;mf_input_option_value&quot;:&quot;value-1&quot;,&quot;_id&quot;:&quot;7625e83&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;},{&quot;mf_input_option_text&quot;:&quot;\\u0627\\u0646\\u062b\\u0649&quot;,&quot;mf_input_option_value&quot;:&quot;value-2&quot;,&quot;_id&quot;:&quot;227b266&quot;,&quot;mf_input_option_status&quot;:&quot;&quot;,&quot;mf_input_option_selected&quot;:&quot;&quot;}],&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-select.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-select-64b627a\">\n\t\t\t\t\t${ parent.decodeEntities(`\u0627\u0644\u062c\u0646\u0633`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n            \n            <${props.Select}\n                className=${\"mf-input mf-input-select  \" + ( validation.errors['mf-Gender-ar'] ? 'mf-invalid' : '' )}\n                classNamePrefix=\"mf_select\"\n                name=\"mf-Gender-ar\"\n                placeholder=\"${ parent.decodeEntities(`\u0627\u062e\u062a\u0631`) } \"\n                isSearchable=${false}\n                options=${[{\"label\":\"\\u0630\\u0643\\u0631\",\"value\":\"value-1\",\"isDisabled\":false},{\"label\":\"\\u0627\\u0646\\u062b\\u0649\",\"value\":\"value-2\",\"isDisabled\":false}]}\n                value=${parent.getValue(\"mf-Gender-ar\") ? [{\"label\":\"\\u0630\\u0643\\u0631\",\"value\":\"value-1\",\"isDisabled\":false},{\"label\":\"\\u0627\\u0646\\u062b\\u0649\",\"value\":\"value-2\",\"isDisabled\":false}].filter(item => item.value === parent.getValue(\"mf-Gender-ar\"))[0] : []}\n                onChange=${(e)=> parent.handleSelect(e, \"mf-Gender-ar\")}\n                ref=${() => {\n\t\t\t\t                    register({ name: \"mf-Gender-ar\" }, parent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true}));\n                    if ( parent.getValue(\"mf-Gender-ar\") === '' && false ) {\n\t\t\t\t    parent.setValue( 'mf-Gender-ar', '', true );\n                        parent.handleChange({\n                            target: {\n                                name: 'mf-Gender-ar',\n                                value: ''\n                            }\n                        });\n                    }\n                }}\n                \/>\n\n            \t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-Gender-ar\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d091032\" data-id=\"d091032\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-d6cf151 elementor-widget elementor-widget-mf-text\" data-id=\"d6cf151\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-Position-ar&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-d6cf151\">\r\n\t\t\t\t\t${ parent.decodeEntities(`\u0627\u0644\u0648\u0638\u064a\u0641\u0629 \u0627\u0644\u062a\u064a \u062a\u0648\u062f \u0627\u0644\u062a\u0642\u062f\u0645 \u0644\u0647\u0627`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input \"\r\n\t\t\t\tid=\"mf-input-text-d6cf151\"\r\n\t\t\t\tname=\"mf-Position-ar\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`\u0623\u062f\u062e\u0644 \u0627\u0644\u0645\u0633\u0645\u0649 \u0627\u0644\u0648\u0638\u064a\u0641\u064a \u0627\u0644\u062e\u0627\u0635 \u0628\u0643`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-Position-ar'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-Position-ar\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-3a62ea78 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3a62ea78\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-676e8797\" data-id=\"676e8797\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-4bda9f5 elementor-widget elementor-widget-mf-text\" data-id=\"4bda9f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-country-ar&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-4bda9f5\">\r\n\t\t\t\t\t${ parent.decodeEntities(`\u0627\u0644\u062f\u0648\u0644\u0629`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-4bda9f5\"\r\n\t\t\t\tname=\"mf-country-ar\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`\u0627\u0644\u062f\u0648\u0644\u0629`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-country-ar'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-country-ar\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2c9a43de\" data-id=\"2c9a43de\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-257c28a elementor-widget elementor-widget-mf-text\" data-id=\"257c28a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-city-ar&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-257c28a\">\r\n\t\t\t\t\t${ parent.decodeEntities(`\u0627\u0644\u0645\u062f\u064a\u0646\u0629`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-257c28a\"\r\n\t\t\t\tname=\"mf-city-ar\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`\u0627\u0644\u0645\u062f\u064a\u0646\u0629`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-city-ar'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-city-ar\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-7c3fb63 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7c3fb63\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0563c5f\" data-id=\"0563c5f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-42e03de elementor-widget elementor-widget-mf-file-upload\" data-id=\"42e03de\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-file-upload&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-file-upload.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-file-upload-42e03de\">\r\n\t\t\t\t\t${ parent.decodeEntities(`\u0631\u0641\u0639 \u0627\u0644\u0633\u064a\u0631\u0629 \u0627\u0644\u0630\u0627\u062a\u064a\u0629`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<div className=\"mf-file-upload-container multi-option-input-type\">\r\n\t\t\t\t<input\r\n\t\t\t\t\ttype=\"file\"\r\n\t\t\t\t\tclassName=\"mf-input mf-input-file-upload \"\r\n\t\t\t\t\tid=\"mf-input-file-upload-42e03de\" \r\n\t\t\t\t\tname=\"mf-file-upload\" \r\n\t\t\t\t\tmultiple\t\t\t\t\taccept=\".jpg, .jpeg, .gif, .png, .pdf, .doc, .docx\"\r\n\t\t\t\t\tonInput=${ parent.handleFileUpload }\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-file-upload'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"required\":true,\"file_types\":[\".jpg\",\".jpeg\",\".gif\",\".png\",\".pdf\",\".doc\",\".docx\"],\"type_message\":\"Invalid file extension\",\"size_limit\":-1,\"limit_message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\"}, el) }\r\n\t\t\t\t\t\/>\r\n\t\t\t\t<label htmlFor=\"mf-input-file-upload-42e03de\" className=\"mf-input-file-upload-label metform-btn\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`\u0627\u062e\u062a\u0631 \u0645\u0644\u0641\u064b\u0627`) } <\/span><i aria-hidden=\"true\" className=\"jki jki-upload-line\"><\/i>\t\t\t\t<\/label>\r\n\t\t\t\t<div className=\"mf-file-name\">\r\n\t\t\t\t\t${\r\n\t\t\t\t\t\t(parent.state.formData['mf-file-upload'] || []).length > 0\r\n\t\t\t\t\t\t? parent.state.formData['mf-file-upload'].map((file, idx) => html`\r\n\t\t\t\t\t\t\t<span className=\"mf-file-name-item\" key=${idx}>\r\n\t\t\t\t\t\t\t\t<span>${file.name}<\/span>\r\n\t\t\t\t\t\t\t\t<span \r\n\t\t\t\t\t\t\t\t\tclassName=\"mf-file-remove\" \r\n\t\t\t\t\t\t\t\t\tonClick=${() => parent.removeUploadedFile('mf-file-upload', idx)}\r\n\t\t\t\t\t\t\t\t\ttitle=\"Remove\"\r\n\t\t\t\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t<label className=\"mf-file-cross\">\u00d7<\/label>\r\n\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t`)\r\n\t\t\t\t\t\t: html`<span>${parent.getFileLabel('mf-file-upload', '\u0644\u0645 \u064a\u062a\u0645 \u0627\u062e\u062a\u064a\u0627\u0631 \u0645\u0644\u0641')}<\/span>`\r\n\t\t\t\t\t}\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-file-upload\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t<span className=\"mf-input-help\"> ${ parent.decodeEntities(`(File Upload - PDF, DOC)`) }  <\/span>\t\t<\/div>\r\n\r\n\t\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ad1d006\" data-id=\"ad1d006\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-7ea4696 elementor-widget elementor-widget-mf-text\" data-id=\"7ea4696\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-exp-ar&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-7ea4696\">\r\n\t\t\t\t\t${ parent.decodeEntities(`\u0639\u062f\u062f \u0633\u0646\u0648\u0627\u062a \u0627\u0644\u062e\u0628\u0631\u0629 \u0630\u0627\u062a \u0627\u0644\u0635\u0644\u0629`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input mf-conditional-input\"\r\n\t\t\t\tid=\"mf-input-text-7ea4696\"\r\n\t\t\t\tname=\"mf-exp-ar\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`\u0639\u062f\u062f \u0633\u0646\u0648\u0627\u062a \u0627\u0644\u062e\u0628\u0631\u0629`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-exp-ar'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-exp-ar\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-inner-section elementor-element elementor-element-1f6daab4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1f6daab4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54f54cbc\" data-id=\"54f54cbc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;profecient_background_motion_effects_toggle&quot;:0,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-7e5c045e elementor-widget elementor-widget-mf-textarea\" data-id=\"7e5c045e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-Cover-Letter&quot;,&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-textarea.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-area-7e5c045e\">\r\n\t\t\t\t\t${ parent.decodeEntities(`\u0631\u0633\u0627\u0644\u0629 \u0637\u0644\u0628 \u0627\u0644\u0648\u0638\u064a\u0641\u0629`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<textarea className=\"mf-input mf-textarea mf-conditional-input\" id=\"mf-input-text-area-7e5c045e\"\r\n\t\t\t\tname=\"mf-Cover-Letter\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`\u0639\u0631\u0641 \u0628\u0646\u0641\u0633\u0643 \u0648\u0623\u0628\u0631\u0632 \u0645\u0647\u0627\u0631\u0627\u062a\u0643 \u0648\u062e\u0628\u0631\u0627\u062a\u0643 \u0627\u0644\u062a\u064a \u0633\u062a\u0633\u0627\u0647\u0645 \u0628\u0647\u0627 \u0641\u064a \u0627\u0644\u0641\u0631\u064a\u0642`) } \"\r\n\t\t\t\tcols=\"30\" rows=\"10\"\r\n\t\t\t\t\t\t\t\t\tonInput=${ parent.handleChange }\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-Cover-Letter'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"\\u0647\\u0630\\u0627 \\u0627\\u0644\\u062d\\u0642\\u0644 \\u0645\\u0637\\u0644\\u0648\\u0628\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t><\/textarea>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-Cover-Letter\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-4429ff08 elementor-widget elementor-widget-mf-recaptcha\" data-id=\"4429ff08\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-recaptcha.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\n\t\t\t\t\t<div\n\t\t\t\t\t\tclassName=\"g-recaptcha \"\n\t\t\t\t\t\tid=\"g-recaptcha\"\n\t\t\t\t\t\tdata-sitekey=\"dummy\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-callback=\"handleReCAPTCHA_${this.state.recaptcha_uid}\"\n\t\t\t\t\t\t\tdata-expired-callback=\"handleReCAPTCHA_${this.state.recaptcha_uid}\"\n\t\t\t\t\t\t\tdata-error-callback=\"handleReCAPTCHA_${this.state.recaptcha_uid}\"\n\t\t\t\t\t\t\taria-invalid=${validation.errors['g-recaptcha-response'] ? 'true' : 'false'}\n\t\t\t\t\t\t\t\t\t\t\t\t><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\"\n\t\t\t\t\t\t\tname=\"g-recaptcha-response\"\n\t\t\t\t\t\t\tclassName=\"mf-input mf-mobile-hidden\"\n\t\t\t\t\t\t\tvalue=${parent.getValue('g-recaptcha-response')}\n\t\t\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"reCAPTCHA is required.\",\"required\":true}, el)}\n\t\t\t\t\t\t\t\/>\n\n\t\t\t\t\t\t<${validation.ErrorMessage} errors=${validation.errors} name=\"g-recaptcha-response\" as=${html`<span className=\"mf-error-message\"><\/span>`} \/>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-5aab362 mf-btn--tablet-justify mf-btn--mobile-justify mf-btn--center elementor-widget elementor-widget-mf-button\" data-id=\"5aab362\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;profecient_custom_cursor_toggle&quot;:false,&quot;profecient_parallax_effects_toggle&quot;:0,&quot;profecient_mouse_effects_toggle&quot;:0}\" data-widget_type=\"mf-button.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper \" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`\u0627\u0631\u0633\u0640\u0640\u0627\u0644`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u0648\u0638\u0627\u0626\u0641 \u0627\u0646\u0636\u0645 \u0644\u0641\u0631\u064a\u0642\u0646\u0627! \u0646\u062d\u0646 \u0646\u0639\u0645\u0644 \u0639\u0644\u0649 \u0628\u0646\u0627\u0621 \u0645\u0633\u062a\u0642\u0628\u0644 \u0627\u0644\u0627\u0628\u062a\u0643\u0627\u0631 \u0627\u0644\u0637\u0628\u064a \u0648\u0627\u0644\u0645\u062e\u062a\u0628\u0631\u064a \u0641\u064a \u062c\u0645\u064a\u0639 \u0623\u0646\u062d\u0627\u0621 \u0627\u0644\u0645\u0646\u0637\u0642\u0629 &#8211; \u0648\u0646\u0628\u062d\u062b \u0639\u0646 \u0623\u0634\u062e\u0627\u0635 \u0645\u062a\u062d\u0645\u0633\u064a\u0646 \u0644\u0644\u0627\u0646\u0636\u0645\u0627\u0645 \u0625\u0644\u064a\u0646\u0627.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-997","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/al-rabiyah.com\/ar\/wp-json\/wp\/v2\/pages\/997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/al-rabiyah.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/al-rabiyah.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/al-rabiyah.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/al-rabiyah.com\/ar\/wp-json\/wp\/v2\/comments?post=997"}],"version-history":[{"count":18,"href":"https:\/\/al-rabiyah.com\/ar\/wp-json\/wp\/v2\/pages\/997\/revisions"}],"predecessor-version":[{"id":1187,"href":"https:\/\/al-rabiyah.com\/ar\/wp-json\/wp\/v2\/pages\/997\/revisions\/1187"}],"wp:attachment":[{"href":"https:\/\/al-rabiyah.com\/ar\/wp-json\/wp\/v2\/media?parent=997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}